{"id":27766,"date":"2025-04-04T12:48:00","date_gmt":"2025-04-04T15:48:00","guid":{"rendered":"https:\/\/www.fi.uncoma.edu.ar\/?p=27766"},"modified":"2025-04-08T13:26:15","modified_gmt":"2025-04-08T16:26:15","slug":"santiago-villarroel-herramienta-de-diseno-de-aplicaciones-web-para-la-consulta-de-programas-prolog","status":"publish","type":"post","link":"https:\/\/www.fi.uncoma.edu.ar\/index.php\/nuevos-lic-lcc\/santiago-villarroel-herramienta-de-diseno-de-aplicaciones-web-para-la-consulta-de-programas-prolog\/","title":{"rendered":"Santiago Villarroel: Herramienta de dise\u00f1o de aplicaciones Web para la consulta de programas Prolog"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"27766\" class=\"elementor elementor-27766\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c64400f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c64400f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3410869\" data-id=\"3410869\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae51bcb elementor-widget elementor-widget-text-editor\" data-id=\"ae51bcb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p><strong>T\u00edtulo<\/strong>: \u00ab<em>Herramienta de dise\u00f1o de aplicaciones Web para la consulta de programas Prolog\u00bb<\/em><\/p><div><p><strong>D\u00eda y hora:<\/strong> Viernes 4 de abril de 2025<\/p><p><strong>Tesista<\/strong>: Santiago A. Villarroel<\/p><p><strong>Directores<\/strong>:\u00a0 Laura A. Cecchi \u2013 Christian N. Gimenez<\/p><\/div><div><strong>Resumen<\/strong><\/div><div>La Programaci\u00f3n L\u00f3gica (LP) es un paradigma deseable para la introducci\u00f3n de las Ciencias de la Computaci\u00f3n en las escuelas, y para el desarrollo de habilidades de Pensamiento Computacional \u00a0y Pensamiento L\u00f3gico de los ni\u00f1os. Para que la ense\u00f1anza de la LP sea viable, un punto de fundamental importancia es contar con recursos did\u00e1cticos adecuados.<br \/><br \/>En este sentido, se identifica la necesidad de entornos tecnol\u00f3gicos que permitan a los estudiantes interactuar de modo accesible con programas l\u00f3gicos.<br \/><br \/>Actualmente, los estudiantes carecen de herramientas efectivas para mostrar en funcionamiento estos programas, a personas sin conocimiento de la LP. Ofrecer un medio para crear aplicaciones Web que permitan \u00a0consultar \u00a0los programas l\u00f3gicos \u00a0incentivar\u00eda el aprendizaje y facilitar\u00eda la presentaci\u00f3n de sus trabajos a compa\u00f1eros, amigos y familiares.<br \/><br \/>En esta tesis se introduce Prolog Web App Creator. La soluci\u00f3n propuesta permite la creaci\u00f3n de una aplicaci\u00f3n Web personalizada, de manera intuitiva, utilizando elementos visuales que se generan din\u00e1micamente a partir del c\u00f3digo fuente. Estos pueden ser insertados y manipulados por el desarrollador en una vista preliminar del dise\u00f1o de la p\u00e1gina. La herramienta facilita tanto el dise\u00f1o visual de la aplicaci\u00f3n, como la ejecuci\u00f3n de consultas directamente sobre el programa l\u00f3gico ingresado. Una vez completado el proyecto en edici\u00f3n, se puede exportar para generar la p\u00e1gina Web final que puede compartirse f\u00e1cilmente con otros usuarios.<br \/><br \/>Prolog Web App Creator promueve un enfoque constructivista en la ense\u00f1anza de la LP, contribuyendo de manera positiva al aprendizaje, ya que, de este modo, los conceptos abstractos son aplicados a la hora de construir un artefacto tangible, p\u00fablico, y personalizado.<br \/><br \/>Debido a su licencia\u00a0<i>open source<\/i>\u00a0y al \u00e9nfasis puesto en las propiedades de modularidad y separaci\u00f3n de aspectos, es posible, en el futuro, expandir la funcionalidad de la herramienta y desarrollar trabajos relacionados con la misma.<br \/><br \/>Asimismo, se presentan \u00a0ejemplos del uso de la plataforma, mediante los cuales, se ilustra c\u00f3mo un enfoque constructivista resulta en un producto final personalmente significativo, y en un mejor entendimiento de los conceptos de la LP al aplicarlos de modo concreto. Adem\u00e1s, los ejemplos presentan posibles modalidades para el uso de la herramienta en las aulas de nivel primario o secundario.Con este prototipo se busca contribuir al campo de la ense\u00f1anza de la programaci\u00f3n, y especialmente de la LP, ofreciendo una herramienta que facilite la elaboraci\u00f3n de aplicaciones Web que interact\u00faan con un programa l\u00f3gico. As\u00ed, se espera promover la transici\u00f3n de los usuarios y desarrolladores hacia un rol de creadores de tecnolog\u00eda, y no solo consumidores de la misma.<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad68e64 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad68e64\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-15c49f5\" data-id=\"15c49f5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-05cef97 elementor-widget elementor-widget-image\" data-id=\"05cef97\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img width=\"900\" height=\"485\" src=\"https:\/\/www.fi.uncoma.edu.ar\/wp-content\/uploads\/2025\/04\/defensa-santiago-villarroel.jpg\" class=\"attachment-large size-large\" alt=\"Foto del dia de la defensa\" loading=\"lazy\" srcset=\"https:\/\/www.fi.uncoma.edu.ar\/wp-content\/uploads\/2025\/04\/defensa-santiago-villarroel.jpg 900w, https:\/\/www.fi.uncoma.edu.ar\/wp-content\/uploads\/2025\/04\/defensa-santiago-villarroel-300x162.jpg 300w, https:\/\/www.fi.uncoma.edu.ar\/wp-content\/uploads\/2025\/04\/defensa-santiago-villarroel-768x414.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Foto del d\u00eda de la defensa con sus tutores y el tribunal integrado por l@s docentes Lic. Claudia Allan y Lic. Giuliano Marinelli<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-390f034 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"390f034\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d77a8aa\" data-id=\"d77a8aa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d89beb8 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"d89beb8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.fi.uncoma.edu.ar\/index.php\/nuevos-lic-lcc\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver otras tesis LCC FaI<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>El 4 de abril de 2025, el estudiante Santiago Villarroel aprob\u00f3 su tesis de Licenciatura en Ciencias de la Computaci\u00f3n.<br \/>\n\u00a1Felicitaciones Licenciado!<\/p>\n","protected":false},"author":4,"featured_media":27773,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[38,14],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/www.fi.uncoma.edu.ar\/wp-content\/uploads\/2025\/04\/defensa-santiago-villarroel.jpg",900,485,false],"thumbnail":["https:\/\/www.fi.uncoma.edu.ar\/wp-content\/uploads\/2025\/04\/defensa-santiago-villarroel-150x150.jpg",150,150,true],"medium":["https:\/\/www.fi.uncoma.edu.ar\/wp-content\/uploads\/2025\/04\/defensa-santiago-villarroel-300x162.jpg",300,162,true],"medium_large":["https:\/\/www.fi.uncoma.edu.ar\/wp-content\/uploads\/2025\/04\/defensa-santiago-villarroel-768x414.jpg",768,414,true],"large":["https:\/\/www.fi.uncoma.edu.ar\/wp-content\/uploads\/2025\/04\/defensa-santiago-villarroel.jpg",900,485,false],"1536x1536":["https:\/\/www.fi.uncoma.edu.ar\/wp-content\/uploads\/2025\/04\/defensa-santiago-villarroel.jpg",900,485,false],"2048x2048":["https:\/\/www.fi.uncoma.edu.ar\/wp-content\/uploads\/2025\/04\/defensa-santiago-villarroel.jpg",900,485,false]},"uagb_author_info":{"display_name":"editor Fai","author_link":"https:\/\/www.fi.uncoma.edu.ar\/index.php\/author\/editorfai\/"},"uagb_comment_info":0,"uagb_excerpt":"El 4 de abril de 2025, el estudiante Santiago Villarroel aprob\u00f3 su tesis de Licenciatura en Ciencias de la Computaci\u00f3n. \u00a1Felicitaciones Licenciado!","_links":{"self":[{"href":"https:\/\/www.fi.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/27766"}],"collection":[{"href":"https:\/\/www.fi.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fi.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fi.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fi.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=27766"}],"version-history":[{"count":10,"href":"https:\/\/www.fi.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/27766\/revisions"}],"predecessor-version":[{"id":27777,"href":"https:\/\/www.fi.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/27766\/revisions\/27777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fi.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/27773"}],"wp:attachment":[{"href":"https:\/\/www.fi.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=27766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fi.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=27766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fi.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=27766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}